{"id":2535,"date":"2019-11-21T11:12:58","date_gmt":"2019-11-21T10:12:58","guid":{"rendered":"http:\/\/www.omiplace.com\/chuck\/?p=2535"},"modified":"2019-11-21T11:13:00","modified_gmt":"2019-11-21T10:13:00","slug":"the-toyota-way-jeffrey-k-liker","status":"publish","type":"post","link":"https:\/\/www.omiplace.com\/chuck\/2019\/11\/21\/the-toyota-way-jeffrey-k-liker\/","title":{"rendered":"The Toyota Way &#8211; Jeffrey K.Liker"},"content":{"rendered":"\n<p>Dans ce livre nous allons trouver les piliers de la pens\u00e9e du Lean. C&rsquo;est un ouvrage cl\u00e9s que tous les acteurs qui sont dans le Lean on lu ou connaissent. Ce qui est particularisent int\u00e9ressant ce sont les 14 elements pr\u00e9sent dans l&rsquo;executive summary. Le voici <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.omiplace.com\/chuck\/wp-content\/uploads\/2019\/11\/TheToyotaWay.png\" alt=\"\" class=\"wp-image-2536\" width=\"126\" height=\"174\" srcset=\"https:\/\/www.omiplace.com\/chuck\/wp-content\/uploads\/2019\/11\/TheToyotaWay.png 579w, https:\/\/www.omiplace.com\/chuck\/wp-content\/uploads\/2019\/11\/TheToyotaWay-217x300.png 217w\" sizes=\"(max-width: 126px) 100vw, 126px\" \/><figcaption>The Toyota Way<\/figcaption><\/figure><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Philosophie long terme<\/li><li>Le bon processus va produire les bons r\u00e9sultats<ul><li>Cr\u00e9er un flux continue pour permettre aux probl\u00e8mes d&rsquo;apparaitre<\/li><li>Utiliser un syst\u00e8me ou les \u00e9l\u00e9ments sont tir\u00e9s pour \u00e9viter la surproduction<\/li><li>Lisser le travail avec des boites de lissage<\/li><li>Construire une culture d&rsquo;arret lorsqu&rsquo;un probl\u00e8me est d\u00e9tect\u00e9<\/li><li>Standardiser les taches sont la fondation d&rsquo;une am\u00e9lioration et d&rsquo;une implication des personnes<\/li><li>Utiliser des contr\u00f4les visuels<\/li><li>Utiliser uniquement des technologies \u00e9prouv\u00e9es qui servent les personnes et les processus<\/li><\/ul><\/li><li>Ajouter de la valeur \u00e0 l&rsquo;organisation par le d\u00e9veloppement des personnes et des partenaires<ul><li>Faite grandir des leaders qui comprendront et vivrons selon cette philosophie et l&rsquo;enseignerons aux autres<\/li><li>D\u00e9velopper des personnes et des \u00e9quipes exceptionnelles qui suivent la philosophie de l&rsquo;entreprise<\/li><li>Respecter le r\u00e9seau \u00e9tendu de fournisseur et partenaires en les posant des challenges et en les aidant \u00e0 s&rsquo;am\u00e9liorer<\/li><\/ul><\/li><li>La r\u00e9solution de la cause racine des probl\u00e8mes conduit les organisations \u00e0 apprendre<ul><li>Aller sur place pour comprendre la situation (genchi genbutsu)<\/li><li>Prendre les d\u00e9cisions lentement par des consensus en consid\u00e9rant toutes les options et impl\u00e9menter les d\u00e9cisions rapidement<\/li><li>Devenir une organisation apprenante \u00e0 travers une pens\u00e9e implacable (hansei \/ Reconnaissance des ses erreurs) et des am\u00e9liorations continues (kaizen)<\/li><\/ul><\/li><\/ul>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans ce livre nous allons trouver les piliers de la pens\u00e9e du Lean. C&rsquo;est un ouvrage cl\u00e9s que tous les acteurs qui sont dans le Lean on lu ou connaissent. Ce qui est particularisent&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":2536,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-2535","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-livres-pro"],"_links":{"self":[{"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/posts\/2535"}],"collection":[{"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/comments?post=2535"}],"version-history":[{"count":1,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/posts\/2535\/revisions"}],"predecessor-version":[{"id":2537,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/posts\/2535\/revisions\/2537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/media\/2536"}],"wp:attachment":[{"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/media?parent=2535"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/categories?post=2535"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omiplace.com\/chuck\/wp-json\/wp\/v2\/tags?post=2535"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}